{"id":56609,"date":"2024-10-01T16:19:42","date_gmt":"2024-10-01T16:19:42","guid":{"rendered":"https:\/\/de-prime.com\/?p=56609"},"modified":"2024-10-01T16:42:10","modified_gmt":"2024-10-01T16:42:10","slug":"kuppel-familienzelt-8-personen-blau-quick-release","status":"publish","type":"product","link":"https:\/\/de-prime.com\/index.php\/product\/kuppel-familienzelt-8-personen-blau-quick-release\/","title":{"rendered":"Kuppel-Familienzelt 8 Personen Blau Quick Release"},"content":{"rendered":"<p>Dieses moderne Familienzelt sch\u00fctzt vor unangenehmen Wetter und bietet einen komfortablen Platz bei Abenteuern. Rundum wasserdichtes Design: Aus Polyester mit PU-Beschichtung gefertigt, ist dieses Campingzelt wasser- und winddicht. Die versiegelten N\u00e4hte verhindern effektiv das Eindringen von Regenwasser, w\u00e4hrend die strapazierf\u00e4hige Bodenplane f\u00fcr ein trockenes und komfortables Interieur sorgt.Quick-Release-System: Dank des Quick-Release-Systems l\u00e4sst sich das Zelt m\u00fchelos aufbauen! Lege das Zelt auf den Boden, ziehe das vormontierte Gest\u00e4nge heraus, bis es einrastet, und schon ist das Zelt einsatzbereit!Abnehmbares \u00dcberzelt: Das abnehmbare \u00dcberzelt l\u00e4sst sich an der Zeltoberseite befestigen, um Wetterschutz zu bieten und Privatsph\u00e4re zu schaffen.Praktischer Zugang zum Stromkabel: Dank des E-Anschlusses kannst du ganz einfach ein Verl\u00e4ngerungskabel von einer externen Stromquelle an dein Zelt anschlie\u00dfen.Leicht und tragbar: Dank des faltbaren und leichten Designs l\u00e4sst sich das Zelt einfach verpacken und in der mitgelieferten Tragetasche m\u00fchelos verstauen und transportieren. Achtung:Halte alle Flammen und W\u00e4rmequellen von diesem Zeltstoff fern.<\/p>\n<ul>\n<li>Farbe: Blau<\/li>\n<li>Material: 190T Polyester mit PU-Beschichtung<\/li>\n<li>Gesamtabmessungen: 438 x 268 x 210 cm (L x B x H)<\/li>\n<li>Packma\u00df: 117 x 27,5 x 27 cm (L x B x H)<\/li>\n<li>Schlafplatz: 8 Personen<\/li>\n<li>Gewicht: 11,9 kg<\/li>\n<li>Zelttyp: Familienzelt<\/li>\n<li>Form: Kuppel<\/li>\n<li>Anzahl der Schlafkabinen: 2<\/li>\n<li>Anzahl der Eing\u00e4nge: 2<\/li>\n<li>Anzahl der Fenster: 4<\/li>\n<li>Eingang mit doppeltem Rei\u00dfverschluss<\/li>\n<li>Schnellwechselsystem<\/li>\n<li>Mit abnehmbarem \u00dcberzelt<\/li>\n<li>Mit E-Anschluss<\/li>\n<li>Mit innerem Vorhang<\/li>\n<li>Zusammenbau erforderlich: Ja<\/li>\n<li><strong>Lieferung umfasst:<\/strong><\/li>\n<li>1 x Zelt<\/li>\n<li>1 x Zelt-Regendach<\/li>\n<li>1 x Tragetasche<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Farbe: Blau<\/li>\n<li>Material: 190T Polyester mit PU-Beschichtung<\/li>\n<li>Gesamtabmessungen: 438 x 268 x 210 cm (L x B x H)<\/li>\n<li>Packma\u00df: 117 x 27,5 x 27 cm (L x B x H)<\/li>\n<li>Schlafplatz: 8 Personen<\/li>\n<li>Gewicht: 11,9 kg<\/li>\n<li>Zelttyp: Familienzelt<\/li>\n<li>Form: Kuppel<\/li>\n<li>Anzahl der Schlafkabinen: 2<\/li>\n<li>Anzahl der Eing\u00e4nge: 2<\/li>\n<li>Anzahl der Fenster: 4<\/li>\n<li>Eingang mit doppeltem Rei\u00dfverschluss<\/li>\n<li>Schnellwechselsystem<\/li>\n<li>Mit abnehmbarem \u00dcberzelt<\/li>\n<li>Mit E-Anschluss<\/li>\n<li>Mit innerem Vorhang<\/li>\n<li>Zusammenbau erforderlich: Ja<\/li>\n<li><strong>Lieferung umfasst:<\/strong><\/li>\n<li>1 x Zelt<\/li>\n<li>1 x Zelt-Regendach<\/li>\n<li>1 x Tragetasche<\/li>\n<\/ul>\n","protected":false},"featured_media":10000056609,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[6859,6837,6836,6987],"product_tag":[],"class_list":{"0":"post-56609","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-camping-wandern","7":"product_cat-outdoor-aktivitaeten","8":"product_cat-sportartikel","9":"product_cat-zelte","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple","17":"add-to-wishlist-after_add_to_cart"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/de-prime.com\/index.php\/wp-json\/wp\/v2\/product\/56609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/de-prime.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/de-prime.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/de-prime.com\/index.php\/wp-json\/wp\/v2\/comments?post=56609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/de-prime.com\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/de-prime.com\/index.php\/wp-json\/wp\/v2\/media?parent=56609"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/de-prime.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=56609"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/de-prime.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=56609"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/de-prime.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=56609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}